{"id":61,"date":"2015-07-01T16:40:17","date_gmt":"2015-07-01T16:40:17","guid":{"rendered":"http:\/\/www.einklangmedia.de\/site\/?p=61"},"modified":"2018-02-20T21:40:34","modified_gmt":"2018-02-20T21:40:34","slug":"kristiansandfarsund","status":"publish","type":"post","link":"https:\/\/www.einklangmedia.de\/site\/kristiansandfarsund\/","title":{"rendered":"2.Kristiansand\/Farsund"},"content":{"rendered":"<blockquote><p>Guten Morgen liebe Welt, zeig Dich heut von deiner sch\u00f6nsten Seite, so wie ich es auch tu.<\/p><\/blockquote>\n<p>bin heute um 4:20 aufgewacht und dachte ich hab verschlafen. es war schon so hell drau\u00dfen. ist irgendwie lustig, da\u00df man auf die uhr schauen muss, um zu sehen, wann man schlafen bzw. aufstehen k\u00f6nnte. was f\u00fcr ein hinweis in welchem rhythmus wir leben \ud83d\ude42<\/p>\n<p>bei der f\u00e4hre wurde man nach der h\u00f6he des autos auf fahrstreifen platziert. ich bekam nat\u00fcrlich die 13, wie kann es auch anders sein&#8230;hihi.<\/p>\n<p><a href=\"httpss:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2828fb.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-62\" src=\"httpss:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2828fb-300x183.jpg\" alt=\"DSCF2828fb\" width=\"300\" height=\"183\" srcset=\"https:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2828fb-300x183.jpg 300w, https:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2828fb.jpg 567w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>heute war strandtag und den ersten kaffee hab ich mir dann auch geg\u00f6nnt:<\/p>\n<p><a href=\"httpss:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2855fb.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-63\" src=\"httpss:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2855fb-300x200.jpg\" alt=\"DSCF2855fb\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2855fb-300x200.jpg 300w, https:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2855fb-600x400.jpg 600w, https:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2855fb-1024x682.jpg 1024w, https:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2855fb.jpg 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>in norwegen angekommen, w\u00e4re ich am liebsten an jeder ecke ausgestiegen und h\u00e4tte wie wild fotos machen k\u00f6nnen, aber ich dachte mir. ganz ruhig, es bleibt bestimmt so sch\u00f6n. und so ist es auch, nichtsahnend fahre ich aus einem tunnel und schwuppppsss schon wieder ein postkartenmotiv. das geht hier am laufenden bande so&#8230;.ich bleib erstmal ruhig und genie\u00dfe die atemberaubende landschaft.<\/p>\n<p><a href=\"httpss:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2877fb.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-64\" src=\"httpss:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2877fb-300x170.jpg\" alt=\"DSCF2877fb\" width=\"300\" height=\"170\" srcset=\"https:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2877fb-300x170.jpg 300w, https:\/\/www.einklangmedia.de\/site\/wp-content\/uploads\/2015\/07\/DSCF2877fb.jpg 567w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guten Morgen liebe Welt, zeig Dich heut von deiner sch\u00f6nsten Seite, so wie ich es auch tu. bin heute um 4:20 aufgewacht und dachte ich hab verschlafen. es war schon so hell drau\u00dfen. ist irgendwie lustig, da\u00df man auf die uhr schauen muss, um zu sehen, wann man schlafen bzw. aufstehen k\u00f6nnte. was f\u00fcr ein [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.einklangmedia.de\/site\/wp-json\/wp\/v2\/posts\/61"}],"collection":[{"href":"https:\/\/www.einklangmedia.de\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.einklangmedia.de\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.einklangmedia.de\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.einklangmedia.de\/site\/wp-json\/wp\/v2\/comments?post=61"}],"version-history":[{"count":6,"href":"https:\/\/www.einklangmedia.de\/site\/wp-json\/wp\/v2\/posts\/61\/revisions"}],"predecessor-version":[{"id":800,"href":"https:\/\/www.einklangmedia.de\/site\/wp-json\/wp\/v2\/posts\/61\/revisions\/800"}],"wp:attachment":[{"href":"https:\/\/www.einklangmedia.de\/site\/wp-json\/wp\/v2\/media?parent=61"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.einklangmedia.de\/site\/wp-json\/wp\/v2\/categories?post=61"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.einklangmedia.de\/site\/wp-json\/wp\/v2\/tags?post=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}